{"id":5328,"date":"2007-09-07T01:02:00","date_gmt":"2007-09-06T23:02:00","guid":{"rendered":""},"modified":"2020-09-06T19:09:59","modified_gmt":"2020-09-06T17:09:59","slug":"experiencies-terapia-india","status":"publish","type":"post","link":"https:\/\/www.teiamoner.net\/es\/experiencies-terapia-india\/","title":{"rendered":"Experiencias terapia India"},"content":{"rendered":"<div style=\"font-family: Arial,Helvetica,sans-serif;\">\n<span style=\"font-size: x-small;\">Experiencias de terapia con t\u00edteres<\/span><\/div>\n<div style=\"font-family: Arial,Helvetica,sans-serif;\">\n<span style=\"font-size: large;\">Asia<br \/>\n<\/span><\/div>\n<div style=\"font-family: Arial,Helvetica,sans-serif;\">\n<b><span style=\"font-size: small;\">India<\/span><\/b><\/p>\n<p>\n<b>TERAPIA Y REHABILITACI\u00d3N.&nbsp;<\/b><\/p>\n<div class=\"Estilo6\">\n<span class=\"Estilo7\"><b>Sampa Ghosh.<\/b> <a href=\"http:\/\/www.puppetindia.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.puppetindia.com<\/a><\/span><\/div>\n<div class=\"Estilo6\">\n<\/div>\n<div align=\"justify\">\n<img decoding=\"async\" border=\"0\" src=\"https:\/\/www.teiamoner.net\/wp-content\/uploads\/2007\/09\/image142.jpg\" \/>Algunos pioneros trabajaron con Devi Lal Samar (Fundador del Instituto Cultural en 1952 de Padma Shri), para utilizar t\u00edteres en terapia f\u00edsica y mental.<\/div>\n<div align=\"justify\">\n<\/div>\n<div align=\"justify\">\nEstos experimentos se hizo en Bharatiya Lok Kala Mamdal en Udaipur. La pr\u00e1ctica con ni\u00f1os y adultos les llevaron a unas conclusiones significativas.&nbsp;<\/div>\n<div align=\"justify\">\nPor ejemplo, la gente con relaciones normales con su familia en casa y con sus amigos, constru\u00edan t\u00edteres con caracter\u00edsticas y proporciones est\u00e1ndar; la gente con patrones problem\u00e1ticos de comportamiento con los dem\u00e1s hac\u00eda generalmente a los t\u00edteres con caracter\u00edsticas muy desproporcionadas.<\/div>\n<div style=\"text-align: left;\">\n&nbsp; <\/div>\n<div style=\"text-align: left;\">\nFig.59<\/div>\n<p>En otro ejercicio con un chico problem\u00e1tico que hab\u00eda abandonado la escuela, se utilizaron los t\u00edteres como sustitutos del trabajo de clase.<\/p>\n<p>Con ni\u00f1os tartamudos, el nerviosismo que ten\u00edan al hablar ante un grupo, les hac\u00eda balbucear y encallarse con determinadas consonantes. Estos mismos ni\u00f1os pod\u00edan narrar con \u00e9xito una historia con ayuda de los t\u00edteres de guante manipulados detr\u00e1s de una cortina que los manten\u00eda escondidos de la vista del p\u00fablico.<\/p>\n<p>Los t\u00edteres tambi\u00e9n son utilizados en terapia para tratar handicaps f\u00edsicos, especialmente por aquellos que no tienen alguno de sus miembros. Generalmente se encuentran muy frustrados en la vida por estas deficiencias, como en el caso de los sordos, mudos y ciegos.<\/p>\n<div style=\"text-align: left;\">\n<img decoding=\"async\" border=\"0\" src=\"https:\/\/www.teiamoner.net\/wp-content\/uploads\/2007\/09\/image144.jpg\" \/><\/div>\n<p>&nbsp;En una experiencia en la que se implicaba un ni\u00f1o sin piernas, los t\u00edteres de hilo fueron construidos con las piernas flojas, de modo que con movimientos m\u00e1s leves se pudieran mover los t\u00edteres.<\/p>\n<p>Este ni\u00f1o pod\u00eda presentar un espect\u00e1culo con una narrativa musical de forma aut\u00f3noma, puesto que ten\u00eda una voz muy dulce.<\/p>\n<p>Otro ni\u00f1o ciego pero con todos sus miembros intactos, utiliz\u00f3 t\u00edteres de guante, tallo e hilo, manipulados por \u00e9l mismo y por un ayudante, interpret\u00f3 los di\u00e1logos perfectamente y cant\u00f3 canciones mucho mejor que aquellos que estaban dotados de vista.<\/p>\n<p>Fig.60 <\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Experiencias de terapia con t\u00edteres Asia India TERAPIA Y REHABILITACI\u00d3N. \u2026 <\/p>\n<p class=\"read-more-container\"><a title=\"Experiencias terapia India\" class=\"read-more button\" href=\"https:\/\/www.teiamoner.net\/es\/experiencies-terapia-india\/#more-5328\">seguir leyendo<span class=\"screen-reader-text\">Experiencias terapia India<\/span><\/a><\/p>","protected":false},"author":3,"featured_media":5329,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[119,172,141,142,111],"class_list":["post-5328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-ed-especial","tag-els-titelles-som-especials","tag-experiencies","tag-experiencies-al-mon","tag-terapia","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/posts\/5328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/comments?post=5328"}],"version-history":[{"count":1,"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/posts\/5328\/revisions"}],"predecessor-version":[{"id":5331,"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/posts\/5328\/revisions\/5331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/media\/5329"}],"wp:attachment":[{"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/media?parent=5328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/categories?post=5328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teiamoner.net\/es\/wp-json\/wp\/v2\/tags?post=5328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}